{"id":184,"date":"2021-04-19T14:00:28","date_gmt":"2021-04-19T14:00:28","guid":{"rendered":"https:\/\/demo.artureanec.com\/themes\/agrarium\/?page_id=184"},"modified":"2021-04-19T14:00:28","modified_gmt":"2021-04-19T14:00:28","slug":"pricing-plan","status":"publish","type":"page","link":"https:\/\/demo.artureanec.com\/themes\/agrarium\/pricing-plan\/","title":{"rendered":"Pricing Plans"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"184\" class=\"elementor elementor-184\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed44149 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed44149\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ddbaf74\" data-id=\"ddbaf74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bf935c elementor-widget elementor-widget-agrarium_heading\" data-id=\"4bf935c\" data-element_type=\"widget\" data-widget_type=\"agrarium_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"agrarium-heading-widget\"><h2 class=\"agrarium-heading\"><span class=\"agrarium-subheading\">Prices<\/span><span class=\"agrarium-heading-content\">Choose Your Perfect <br>Pricing Plan<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c5d8fbb\" data-id=\"c5d8fbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7dd3219 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dd3219\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-14602eb\" data-id=\"14602eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-487f3b8 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"487f3b8\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Minimal<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\">Free<\/span>                            <\/div>\n\n                                                    <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">1 Buffet table<\/div>\n                                                                    <div class=\"price-item-custom-field \">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field \">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b49b9bb\" data-id=\"b49b9bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64b1250 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"64b1250\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Basic<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">15<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/mo<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">5 Buffet tables<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field \">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca53b87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca53b87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d94cb1\" data-id=\"0d94cb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a68d58c elementor-widget elementor-widget-agrarium_heading\" data-id=\"a68d58c\" data-element_type=\"widget\" data-widget_type=\"agrarium_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"agrarium-heading-widget\"><h2 class=\"agrarium-heading\"><span class=\"agrarium-subheading\">Pricing Tables <\/span><span class=\"agrarium-heading-content\">Pricing Plans for you<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06b145a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06b145a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5c2c2c5\" data-id=\"5c2c2c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a57f3 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"41a57f3\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Minimal<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\">Free<\/span>                            <\/div>\n\n                                                    <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">1 Buffet table<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">CustomFarming rules<\/div>\n                                                                    <div class=\"price-item-custom-field \">Real-time rate shopping<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 freight shipments \/ month<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5fe7080\" data-id=\"5fe7080\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb80386 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"bb80386\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item active price-item-type-standard\">\n                <span class=\"price-item-best-choice\">Best Choice<\/span>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Optimal<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">15<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/month<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">5 warehouse<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">CustomFarming rules<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Real-time rate shopping<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 freight shipments \/ month<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47266a6\" data-id=\"47266a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96a5c2f elementor-widget elementor-widget-agrarium_price_item\" data-id=\"96a5c2f\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Premium<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">35<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/month<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">10 Buffet table<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">CustomFarming rules<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Real-time rate shopping<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">100 freight shipments \/ month<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af04eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af04eea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-432a3af\" data-id=\"432a3af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ab0d07b elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab0d07b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5829041\" data-id=\"5829041\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebd778d elementor-widget elementor-widget-agrarium_heading\" data-id=\"ebd778d\" data-element_type=\"widget\" data-widget_type=\"agrarium_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"agrarium-heading-widget\"><h2 class=\"agrarium-heading\"><span class=\"agrarium-subheading\">Pricing Tables <\/span><span class=\"agrarium-heading-content\">Pricing Plans <br>for your Business<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dd8ebe5\" data-id=\"dd8ebe5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2c85e4 elementor-widget elementor-widget-text-editor\" data-id=\"d2c85e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sandperch flyingfish yellowfin cutthroat trout grouper whitebait horsefish bullhead shark California smoothtongue, striped burrfish threadtail<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-15a46b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15a46b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-45a78e6\" data-id=\"45a78e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c98d144 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"c98d144\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Minimal<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\">Free<\/span>                            <\/div>\n\n                                                    <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">1 Buffet table<\/div>\n                                                                    <div class=\"price-item-custom-field \">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field \">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ede4017\" data-id=\"ede4017\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6676e0 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"f6676e0\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Basic<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">15<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/mo<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">5 Buffet tables<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field \">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6262e96\" data-id=\"6262e96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba0c517 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"ba0c517\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                <span class=\"price-item-best-choice\">Best Choice<\/span>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Optimal<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">35<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/mo<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">5 Buffet tables<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ee10347\" data-id=\"ee10347\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d72fc95 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"d72fc95\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-standard\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Premium<\/div><\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">75<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/mo<\/div>                        <\/div>\n                                                <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field  active\">5 Buffet tables<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Guests room<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">Real-time delivery<\/div>\n                                                                    <div class=\"price-item-custom-field  active\">100 person crockery<\/div>\n                                                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c99f9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c99f9e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f691e0\" data-id=\"4f691e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec92429 elementor-widget elementor-widget-agrarium_heading\" data-id=\"ec92429\" data-element_type=\"widget\" data-widget_type=\"agrarium_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"agrarium-heading-widget\"><h2 class=\"agrarium-heading\"><span class=\"agrarium-subheading\">Pricing Tables <\/span><span class=\"agrarium-heading-content\">Pricing Plans for you<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57d63fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"57d63fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9ab5111\" data-id=\"9ab5111\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf83221 elementor-widget elementor-widget-agrarium_price_item\" data-id=\"cf83221\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-wide\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Minimal<\/div><\/div><div class=\"price-item-description\">Gar mail-cheeked fish glass knifefish Norwegian Atlantic\n\n<\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\">Free<\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-331cdfa elementor-widget elementor-widget-agrarium_price_item\" data-id=\"331cdfa\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item active price-item-type-wide\">\n                <span class=\"price-item-best-choice\">Best Choice<\/span>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Optimal<\/div><\/div><div class=\"price-item-description\"> Pomfret: vendace combtooth blenny black dragonfish\n\n<\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">15<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/month<\/div>                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3b105d elementor-widget elementor-widget-agrarium_price_item\" data-id=\"f3b105d\" data-element_type=\"widget\" data-widget_type=\"agrarium_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"agrarium-price-item-widget\">            \n            <div class=\"price-item price-item-type-wide\">\n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Premium<\/div><\/div><div class=\"price-item-description\">Scat bighead carp silver dollar platyfish northern lampfish\n<\/div><div class=\"price-item-image\"><\/div>                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">35<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/month<\/div>                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"agrarium-button\" href=\"https:\/\/demo.artureanec.com\/themes\/agrarium\/contacts\" >Get Started<\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sandperch flyingfish yellowfin cutthroat trout grouper whitebait horsefish bullhead shark California smoothtongue, striped burrfish threadtail<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-184","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/pages\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/pages\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.artureanec.com\/themes\/agrarium\/wp-json\/wp\/v2\/media?parent=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}